{"id":22985,"date":"2020-04-23T12:10:34","date_gmt":"2020-04-23T12:10:34","guid":{"rendered":"https:\/\/kulaberlin.com\/product\/via-baker\/"},"modified":"2020-04-23T12:10:34","modified_gmt":"2020-04-23T12:10:34","slug":"via-baker","status":"publish","type":"product","link":"https:\/\/kulaberlin.com\/it\/product\/via-baker\/","title":{"rendered":"VIA BAKER"},"content":{"rendered":"<div class=\"woocommerce-product-details__short-description\">\n<p>Questo vaso da fiori \u00e8 realizzato con una miscela di cemento. \u00c8 possibile creare vasi marmorizzati e colorati utilizzando i migliori pigmenti naturali. Essendo unici, presentano leggere differenze nei colori. Si tratta di un prodotto unico realizzato a mano. Realizzato a Victoria Stadt, Berlino.  <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Questo vaso da fiori \u00e8 realizzato con una miscela di cemento. \u00c8 possibile creare vasi marmorizzati e colorati utilizzando i migliori pigmenti naturali. Essendo unici, presentano leggere differenze nei colori. Si tratta di un prodotto unico realizzato a mano. Realizzato a Victoria Stadt, Berlino.  <\/p>\n","protected":false},"featured_media":11571,"template":"","meta":[],"product_brand":[],"product_cat":[899],"product_tag":[],"class_list":{"0":"post-22985","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-art","7":"product_shipping_class-beni-pesanti-2-kg","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/product\/22985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/media\/11571"}],"wp:attachment":[{"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/media?parent=22985"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/product_brand?post=22985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/product_cat?post=22985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kulaberlin.com\/it\/wp-json\/wp\/v2\/product_tag?post=22985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}